{"id":771,"date":"2019-08-22T16:37:51","date_gmt":"2019-08-22T16:37:51","guid":{"rendered":"https:\/\/rrenjettona.al\/?p=771"},"modified":"2019-08-22T16:37:51","modified_gmt":"2019-08-22T16:37:51","slug":"simbolika-e-germave","status":"publish","type":"post","link":"https:\/\/rrenjettona.al\/index.php\/2019\/08\/22\/simbolika-e-germave\/","title":{"rendered":"Simbolika e g\u00ebrmave"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;772&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<strong><em>Fjalet ky\u00e7<\/em><\/strong><em>&#8211; simbolika, germat, hieroglife, shkruar, vizatonin, lexoheshin, figurat.<\/em>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<strong>Fusha<\/strong>: Gjuh\u00ebsi<\/p>\n<p><strong>Periudha<\/strong> :<\/p>\n<p><strong>Autori<\/strong> : Fredi Balaj[\/vc_column_text]<div class=\"aio-icon-component    style_1\"><a class=\"aio-icon-box-link\" href=\"https:\/\/rrenjettona.al\/wp-content\/uploads\/2019\/08\/Fredi-Balaj_Simbolika-e-germave.pdf\" target=\"_blank\" rel=\"noopener\" ><div id=\"Info-box-wrap-9101\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:48px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/rrenjettona.al\/wp-content\/uploads\/2018\/12\/Pdflogogt.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-9101 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Studimi<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/a><\/div> <!-- aio-icon-component -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;772&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]Fjalet ky\u00e7&#8211; simbolika, germat, hieroglife, shkruar, vizatonin, lexoheshin, figurat.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]Fusha: Gjuh\u00ebsi Periudha : Autori : Fredi Balaj[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-771","post","type-post","status-publish","format-standard","hentry","category-gjuhesi","category-16","description-off"],"_links":{"self":[{"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/posts\/771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/comments?post=771"}],"version-history":[{"count":1,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/posts\/771\/revisions"}],"predecessor-version":[{"id":773,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/posts\/771\/revisions\/773"}],"wp:attachment":[{"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/media?parent=771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/categories?post=771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/tags?post=771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}