{"id":523,"date":"2019-04-30T16:09:35","date_gmt":"2019-04-30T16:09:35","guid":{"rendered":"https:\/\/rrenjettona.al\/?p=523"},"modified":"2019-05-08T08:18:49","modified_gmt":"2019-05-08T08:18:49","slug":"liber-i-permbledhjeve","status":"publish","type":"post","link":"https:\/\/rrenjettona.al\/index.php\/2019\/04\/30\/liber-i-permbledhjeve\/","title":{"rendered":"Lib\u00ebr i p\u00ebrmbledhjeve"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;524&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; image_hovers=&#8221;false&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><a class=\"aio-icon-box-link\" href=\"https:\/\/rrenjettona.al\/wp-content\/uploads\/2019\/04\/PERMBLEDHJE_FINAL.docx\" target=\"_blank\" rel=\"noopener\" ><div id=\"Info-box-wrap-5824\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:48px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/rrenjettona.al\/wp-content\/uploads\/2018\/12\/Pdflogogt.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5824 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Lib\u00ebr i p\u00ebrmbledhjeve<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/a><\/div> <!-- aio-icon-component -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;524&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; image_hovers=&#8221;false&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":2,"featured_media":524,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-njoftime","category-10","description-off"],"_links":{"self":[{"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/posts\/523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/comments?post=523"}],"version-history":[{"count":4,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/posts\/523\/revisions"}],"predecessor-version":[{"id":530,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/posts\/523\/revisions\/530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/media\/524"}],"wp:attachment":[{"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/media?parent=523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/categories?post=523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rrenjettona.al\/index.php\/wp-json\/wp\/v2\/tags?post=523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}